{"id":2571,"date":"2025-12-09T14:06:07","date_gmt":"2025-12-09T13:06:07","guid":{"rendered":"https:\/\/www.smuzcafe.hu\/?p=2571"},"modified":"2025-12-11T14:08:33","modified_gmt":"2025-12-11T13:08:33","slug":"noonradio-x-smuz-cafe-x-blublublu","status":"publish","type":"post","link":"https:\/\/www.smuzcafe.hu\/de\/noonradio-x-smuz-cafe-x-blublublu\/","title":{"rendered":"Stimmungsvolles Caf\u00e9 mit Terrasse am zentralen Platz Budapests, mit beeindruckendem"},"content":{"rendered":"<p>Morgens legen wir wieder richtig los \u2013 mit noch besserem Kaffee und Keksen \u2013 das sollten Sie sich nicht entgehen lassen!<img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf8a\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t53\/2\/16\/1f38a.png\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2615\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t12\/2\/16\/2615.png\"><\/p>\n\n\n\n<p>NOON.RADIO ist zur\u00fcck, diesmal im Schatten des Parlaments im Sm\u00faz Caf\u00e9. Freut euch auf ein unvergessliches Erlebnis aus Musik, Koffein und einem magischen Ort. Ende September laden wir euch erneut ein, mit einer besonderen Kooperation ins Herz der Hauptstadt zur\u00fcckzukehren. Wir pr\u00e4sentieren BluBluBlu \u2013 eine brandneue Marke, die keine Regeln, sondern ein Erlebnis bietet. Verspielt, frisch, spritzig und frei. Hier trifft der Noon-Vibe auf eine neue Marke. Eine gemeinsame Atmosph\u00e4re, die ihr zum ersten Mal sp\u00fcren k\u00f6nnt.<\/p>\n\n\n\n<p>Wir wissen, dass Sie sich schon auf die mitrei\u00dfende Energie der Breakfast Disco, den cremigen Geschmack eines frisch zubereiteten Lattes und das prickelnde Gef\u00fchl von Eis am Stiel freuen. Die gute Nachricht: Sie m\u00fcssen nicht mehr lange warten!<img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2600\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tee\/2\/16\/2600.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc83\ud83c\udffd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t63\/2\/16\/1f483_1f3fd.png\"><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1\/2\/16\/1f4b8.png\">\u00a0Der Eintritt ist frei!<\/p>\n\n\n\n<p>\ufffd<img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u274c\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5e\/2\/16\/274c.png\">\u00a0Eine Tischreservierung ist nicht m\u00f6glich, aber falls kein Platz mehr frei ist, k\u00f6nnen Sie sich gerne neben uns setzen.<\/p>\n\n\n\n<p>Line-up: KANCS, ZOZ\u00d8<\/p>","protected":false},"excerpt":{"rendered":"<p>Ism\u00e9t reggel tekerj\u00fck fel a hanger\u0151t \u2013 jobbn\u00e1l jobb k\u00e1v\u00e9k \u00e9s s\u00fctik mellett \u2013 valami olyan, amib\u0151l nem akarsz kimaradni! A NOON.RADIO \u00fajra felbukkan, ez\u00fattal a parlament \u00e1rny\u00e9k\u00e1ban a Sm\u00faz Caf\u00e9-ban. K\u00e9sz\u00fclj fel a zene, a koffeinl\u00f6ketek \u00e9s egy var\u00e1zslatos hely felejthetetlen tal\u00e1lkoz\u00e1s\u00e1ra. Szeptember v\u00e9g\u00e9n valami \u00fajra invit\u00e1lunk titeket, egy k\u00fcl\u00f6nleges collabbal t\u00e9r\u00fcnk vissza a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-2571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-korabbi-esemenyek"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/posts\/2571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/comments?post=2571"}],"version-history":[{"count":2,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/posts\/2571\/revisions"}],"predecessor-version":[{"id":2574,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/posts\/2571\/revisions\/2574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/media\/2572"}],"wp:attachment":[{"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/media?parent=2571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/categories?post=2571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smuzcafe.hu\/de\/wp-json\/wp\/v2\/tags?post=2571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}